{"id":3077,"date":"2020-11-12T11:52:39","date_gmt":"2020-11-12T16:52:39","guid":{"rendered":"https:\/\/tecvalcloud.com\/?page_id=3077"},"modified":"2021-04-14T10:59:52","modified_gmt":"2021-04-14T15:59:52","slug":"valvulas-de-alivio-presion-vacio","status":"publish","type":"page","link":"https:\/\/tecvalonline.com\/eng\/valvulas-de-alivio-presion-vacio\/","title":{"rendered":"Pressure &#8211; Vacuum relief valves"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=&#8221;1\/4&#8243;][vc_empty_space][vc_single_image image=&#8221;3812&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221;][vc_single_image image=&#8221;3038&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow_border&#8221; onclick=&#8221;zoom&#8221;][vc_empty_space][vc_column_text]<em>Manufacturing: TECVAL, Colombia<\/em><br \/>\n<em>Support: TECVAL, Colombia<\/em>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space]<div id=\"advanced-tabs-desc-wrap-6920\" class=\"ult_tabs \" style=\" \" data-tabsstyle=\"style1\"\n data-titlebg=\"#cccccc\" data-titlecolor=\"#333333\" data-fullheight=\"off\"\n data-titlehoverbg=\"#1e73be\" data-titlehovercolor=\"#ffffff\"\n data-rotatetabs=\"0\" data-responsivemode=\"Both\" data-animation=\"Slide\"\ndata-activetitle=\"#ffffff\" data-activeicon=\"\" data-activebg=\"#00335f\"  data-respmode=\"Accordion\" data-respwidth=\"400\" data-scroll = \"on\" data-activeindex=\"1\"><ul id=advanced-tabs-wrap-2174 class=\"ult_tabmenu style1 Style_4\" style=\"color:transparent;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;border-bottom-width:0px;\"><li class=\"ult_tab_li ult_tab_style_4  \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#cccccc;border-color:transparent;border-width:0px;border-style:solid;border-top-left-radius:8px;\">\n\t\t\t\t\t<a href=\"#1604299113375-4\" id=\"1604299113375-4\" style=\"color:#333333;;  \" class=\"ult_a \">\n\t\t\t\t\t   <span class=\"ult_tab_main  Both \">\n\t\t\t\t\t    <span class=\"ult_tab_section\">\n\t\t\t\t\t  \t\t<span  data-ultimate-target='#advanced-tabs-wrap-2174 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text ult-responsive\" style=\"\">DESCRIPTION<\/span>\n\t\t\t\t\t\t   \t<span class=\"aio-icon none ult_tab_iconright\" style=\"color:#74777b;font-size:15px;\">\n\t\t\t\t\t\t   \t<i class=\"   ult_tab_icon\"  ><\/i>\n\t\t\t\t\t\t   <\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t   <\/span>\n\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4  \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#cccccc;border-color:transparent;border-width:0px;border-style:solid;border-top-right-radius:8px;\">\n\t\t\t\t\t<a href=\"#1604299113458-0\" id=\"1604299113458-0\" style=\"color:#333333;;  \" class=\"ult_a \">\n\t\t\t\t\t   <span class=\"ult_tab_main  Both \">\n\t\t\t\t\t    <span class=\"ult_tab_section\">\n\t\t\t\t\t  \t\t<span  data-ultimate-target='#advanced-tabs-wrap-2174 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text ult-responsive\" style=\"\">BENEFITS<\/span>\n\t\t\t\t\t\t   \t<span class=\"aio-icon none ult_tab_iconright\" style=\"color:#74777b;font-size:15px;\">\n\t\t\t\t\t\t   \t<i class=\"   ult_tab_icon\"  ><\/i>\n\t\t\t\t\t\t   <\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t   <\/span>\n\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><\/ul><div  data-ultimate-target='#advanced-tabs-desc-wrap-6920 .ult_tabcontent .ult_tab_min_contain  p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' class=\"ult_tabcontent ult-responsive style1\" style=\"color:#74777b;\"><div class=\"ult_tab_min_contain \" >\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_column_text]TECVAL vacuum and pressure relief devices are designed and manufactured to ensure liquid storage tank protection.<\/p>\n<p>Devices in aluminum, carbon steel, or stainless steel, and diverse configurations according to process requirements.[\/vc_column_text]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_column_text]<\/p>\n<ul>\n<li>Two year guarantee.<\/li>\n<li>Designed and manufactured according to process conditions and international standards (comply with API 2000).<\/li>\n<li>TECVAL software sizing program ensures adequate selection.<\/li>\n<\/ul>\n<p>[\/vc_column_text]\n\t\t\t<\/div><\/div><\/div><\/div><div class=\"ult_acord advanced-tabs-desc-wrap-6920\">\n   <div class=\"ult-tabto-accordion \" style=\"width:;\"\n    data-titlecolor=\"#333333\"  data-titlebg=\"#cccccc\"\n     data-titlehoverbg=\"#1e73be\" data-titlehovercolor=\"#ffffff\" data-animation=\"Slide\"\n     data-activetitle=\"#ffffff\" data-activeicon=\"\" data-activebg=\"#00335f\" data-scroll = \"on\" data-activeindex=\"1\" >\n     <dl><dt class=\"\">\n        \t<a class=\"ult-tabto-actitle withBorder ult_a\" id=\"1604299113375-4\" style=\"color:#333333;;background-color:#cccccc;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;\" href=\"#1604299113375-4\">\n        \t\t<i class=\"accordion-icon\"><\/i>\n        \t\t\t<span class=\"ult_tab_main ult_ac_mainBoth\">\n\t\t\t\t\t   <span  data-ultimate-target='#advanced-tabs-wrap-2174 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text ult_acordian-text ult-responsive\" style=\";color:inherit \" >DESCRIPTION<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t   <div class=\"aio-icon none \" style=\"color:#74777b;font-size:15px;\" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\">\n\t\t\t\t\t   <i class=\"    ult_tab_icon\"  ><\/i>\n\t\t\t\t\t   <\/div>\n\t\t\t\t\t<\/a><\/dt>\n            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t            <div class=\"ult-tabto-acontent\" style=\"color:#74777b;\">\n\t\t\t               [vc_column_text]TECVAL vacuum and pressure relief devices are designed and manufactured to ensure liquid storage tank protection.<\/p>\n<p>Devices in aluminum, carbon steel, or stainless steel, and diverse configurations according to process requirements.[\/vc_column_text]\n\t\t\t            <\/div>\n        \t<\/dd><dt class=\"\">\n        \t<a class=\"ult-tabto-actitle withBorder ult_a\" id=\"1604299113458-0\" style=\"color:#333333;;background-color:#cccccc;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;\" href=\"#1604299113458-0\">\n        \t\t<i class=\"accordion-icon\"><\/i>\n        \t\t\t<span class=\"ult_tab_main ult_ac_mainBoth\">\n\t\t\t\t\t   <span  data-ultimate-target='#advanced-tabs-wrap-2174 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text ult_acordian-text ult-responsive\" style=\";color:inherit \" >BENEFITS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t   <div class=\"aio-icon none \" style=\"color:#74777b;font-size:15px;\" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\">\n\t\t\t\t\t   <i class=\"    ult_tab_icon\"  ><\/i>\n\t\t\t\t\t   <\/div>\n\t\t\t\t\t<\/a><\/dt>\n            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t            <div class=\"ult-tabto-acontent\" style=\"color:#74777b;\">\n\t\t\t               [vc_column_text]<\/p>\n<ul>\n<li>Two year guarantee.<\/li>\n<li>Designed and manufactured according to process conditions and international standards (comply with API 2000).<\/li>\n<li>TECVAL software sizing program ensures adequate selection.<\/li>\n<\/ul>\n<p>[\/vc_column_text]\n\t\t\t            <\/div>\n        \t<\/dd>\n    \t<\/dl>\n    <!--<div class=\"extraborder\" style=\"background-color:#1e73be\"><\/div>-->\n<\/div>\n\n<\/div>[vc_empty_space]\n\t\t\t<div class=\"ult_dual_button  ult-adjust-bottom-margin to-center  \"  data-response=\"off\" id=\"ult_btn_1938191803\">\n\n\t\t\t<div id=\"dualbtn-1281\" class=\"ulitmate_dual_buttons ult-dual-btn3 ult_main_dualbtn \" data-bcolor=\"#333333\"data-bhcolor=\"\">\n\n\t\t\t<div class=\"ult_dualbutton-wrapper btn-inline place-template bt1 \"><a href=\"https:\/\/tecvalonline.com\/pdf\/productos\/Catalogo%20Valvula%20Presi%c3%b3n%20Vacio.pdf\" target=\"_blank\" rel=\"noopener\"  class=\"ult_ivan_button round-square with-icon icon-before with-text place-template ult_dual1\" style=\";margin-right:px;;background-color:#1e73be !important;; border-color:#333333;border-style:;border-width:0px;border-radius:5px;;\">\n\t\t\t<span class=\"ult-dual-btn-1 Style 2\" style=\"\"  data-bgcolor=\"#1e73be\" data-bghovercolor=\"#bcbcbc\" data-icon_color=\"#ffffff\" data-icon_hover_color=\"#333333\" data-textcolor=\"#ffffff\" data-texthovercolor=\"#333333\" data-iconbgcolor=\"transperent\" data-iconbghovercolor=\"transperent\" data-iconborder=\"transperent\" data-iconhoverborder=\"transperent\" >\n\t\t\t<span class=\"icon-simple icon-left1 ult_btn1span \"  style=\"; \">\n<span class=\"aio-icon btn1icon none \"  style=\"color:#ffffff;font-size:20px;\">\n\t<i class=\"Defaults-download\" ><\/i>\n<\/span><\/span>\n\t\t\t<span class=\"text-btn ult-dual-button-title ult-responsive\"  data-ultimate-target='#dualbtn-1281 .ult-dual-button-title'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"desktop:15px;\"}'  style=\"font-weight:normal;color:#ffffff;\">CATALOG<\/span>\n\n\t\t\t<\/span>\n\t\t\t<\/a><span class=\"middle-text\" style=\"line-height: 1.8em;color:#ffffff;background-color:#1e73be;border-width:0px;\">\n\t\t\t<span class=\"middle-inner\"  ><i class=\"Defaults-ellipsis-v\"><\/i><\/span>\n\t\t\t<\/span>\n\n\t\t\t<\/div>\n\n\t\t\t<div class=\"ult_dualbutton-wrapper btn-inline place-template btn2 \"><a href=\"https:\/\/www.youtube.com\/watch?v=_nqESnMG82U\" target=\"_blank\" rel=\"noopener\"  class=\"ult_ivan_button round-square with-icon icon-after with-text place-template ult_dual2\"  style=\";background-color:#1e73be !important;;margin-left:px;;border-color:#333333;border-style:;border-width:0px;border-radius:5px;\">\n\t\t\t<span class=\"ult-dual-btn-2 Style 2\"  data-bgcolor=\"#1e73be\" data-bghovercolor=\"#bcbcbc\" data-icon_color=\"#ffffff\" data-icon_hover_color=\"#333333\" data-textcolor=\"#ffffff\" data-texthovercolor=\"#333333\" data-iconbgcolor=\"transperent\" data-iconbghovercolor=\"transperent\" data-iconborder=\"transperent\" data-iconhoverborder=\"transperent\" >\n\t\t\t<span class=\"text-btn ult-dual-button-title\" style=\"font-weight:normal;color:#ffffff;\">VIDEO<\/span>\n\n\t\t\t<span class=\"icon-simple icon-right2 ult_btn1span \"  style=\"; \">\n<span class=\"aio-icon btn1icon none \"  style=\"color:#ffffff;font-size:20px;display:inline-block;\">\n\t<i class=\"Defaults-youtube-play\" ><\/i>\n<\/span><\/span>\n\t\t\t<\/span>\n\t\t\t<\/a><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>[vc_empty_space][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_empty_space]<div id=\"ultimate-heading-79536a04643cac30a\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-79536a04643cac30a uvc-9511 \" data-hspacer=\"line_only\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer line_only\" style=\"topheight:1px;\"><span class=\"uvc-headings-line\" style=\"border-style:solid;border-bottom-width:1px;border-color:#ccc;width:autopx;\"><\/span><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-79536a04643cac30a h3'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h3 style=\"font-weight:normal;\">REQUEST PRODUCT<\/h3><\/div><\/div>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2943-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"2943\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/eng\/wp-json\/wp\/v2\/pages\/3077#wpcf7-f2943-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"2943\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.1\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2943-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n\n<h6>DATOS DEL PRODUCTO:\n<\/h6>\n<p><label> Fluido<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"fluido\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"fluido\" \/><\/span> <\/label><br \/>\n<label> Presi\u00f3n de Set<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"presion\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"presion\" \/><\/span> <\/label><br \/>\n<label> Capacidad\/Caudal<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"capacidad\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"capacidad\" \/><\/span> <\/label><br \/>\n<label> Temperatura<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"temperatura\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"temperatura\" \/><\/span> <\/label><br \/>\n<label> % Sobrepresi\u00f3n<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sobrepresion\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"sobrepresion\" \/><\/span> <\/label><br \/>\n<label> Contrapresi\u00f3n Superimpuesta<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"contrapresion\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"contrapresion\" \/><\/span> <\/label><br \/>\n<label> Contrapresi\u00f3n Built Up<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"built\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"built\" \/><\/span> <\/label><br \/>\n<label> Tipo de Conexi\u00f3n Entrada<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tipoentrada\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"tipoentrada\" \/><\/span> <\/label><br \/>\n<label> Tama\u00f1o de Conexi\u00f3n Entrada<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tamanoentrada\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"tamanoentrada\" \/><\/span> <\/label><br \/>\n<label> Tipo de Conexi\u00f3n Salida<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tiposalida\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"tiposalida\" \/><\/span> <\/label><br \/>\n<label> Tama\u00f1o de Conexi\u00f3n Salida<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tamanosalida\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"tamanosalida\" \/><\/span> <\/label><br \/>\n<\/p>\n<h6>DATOS DEL CLIENTE:\n<\/h6>\n<p><label> Nombre y apellido*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"name\" \/><\/span> <\/label><br \/>\n<label> E-mail*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email\" \/><\/span> <\/label><br \/>\n<label> Tel\u00e9fono*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"telefono\" \/><\/span> <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"acepto\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acepto\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Acepto <a target=\"_blank\" href=\"https:\/\/tecvalonline.com\/manejo-de-datos-personales\/\"> Pol\u00edtica de Tratamiento de Datos Personales<\/a><\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"188\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;52px&#8221;]<div id=\"ult-easy-separator-17723844956a04643cad627\" class=\"ult-easy-separator-wrapper ult-responsive ult-top-easy-separator  \" style=\"\" data-vc-row=\"wpb_row\"  data-ultimate-target='#ult-easy-separator-17723844956a04643cad627'  data-responsive-json-new='{\"width\":\"desktop:400px;\"}' ><div class=\"ult-easy-separator-inner-wrapper\"><div class=\"ult-no-animation\" style=\"opacity:0;\"   ><img decoding=\"async\" class=\"ult-easy-separator-img\" alt=\"null\" src=\"https:\/\/tecvalonline.com\/eng\/wp-content\/uploads\/2020\/11\/tecval-separador.png\" \/><\/div><\/div><\/div>[vc_empty_space height=&#8221;52px&#8221;]<div id=\"ult-carousel-29350430876a04643cad6b6\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-16147480116a04643cad66c \" >[vc_single_image image=&#8221;2674&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;zoom&#8221;][vc_single_image image=&#8221;2675&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;zoom&#8221;][vc_single_image image=&#8221;2676&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;zoom&#8221;][vc_single_image image=&#8221;2677&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;zoom&#8221;][vc_single_image image=&#8221;2678&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;zoom&#8221;][vc_single_image image=&#8221;2679&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;zoom&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-16147480116a04643cad66c').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-16147480116a04643cad66c').slick({dots: false,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: true,nextArrow: '<button type=\"button\" role=\"button\" aria-label=\"Next\" style=\"color:#333333; font-size:20px;\" class=\"slick-next default\"><i class=\"ultsl-arrow-right4\"><\/i><\/button>',prevArrow: '<button type=\"button\" role=\"button\" aria-label=\"Previous\" style=\"color:#333333; font-size:20px;\" class=\"slick-prev default\"><i class=\"ultsl-arrow-left4\"><\/i><\/button>',slidesToScroll:6,slidesToShow:6,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 6,\n\t\t\t\t\t\t\t\tslidesToScroll: 6,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 3,\n\t\t\t\t\t\t\t\tslidesToScroll: 3\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 2,\n\t\t\t\t\t\t\t\tslidesToScroll: 2\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#333333;\" class=\"ultsl-record\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/4&#8243;][vc_empty_space][vc_single_image image=&#8221;3812&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221;][vc_single_image image=&#8221;3038&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow_border&#8221; onclick=&#8221;zoom&#8221;][vc_empty_space][vc_column_text]Manufacturing: TECVAL, Colombia Support: TECVAL, Colombia[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space][vc_empty_space][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_empty_space][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;52px&#8221;][vc_empty_space height=&#8221;52px&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-3077","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pressure - Vacuum relief valves - Tecval<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tecvalonline.com\/eng\/valvulas-de-alivio-presion-vacio\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pressure - Vacuum relief valves - Tecval\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column width=&#8221;1\/4&#8243;][vc_empty_space][vc_single_image image=&#8221;3812&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221;][vc_single_image image=&#8221;3038&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow_border&#8221; onclick=&#8221;zoom&#8221;][vc_empty_space][vc_column_text]Manufacturing: TECVAL, Colombia Support: TECVAL, Colombia[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space][vc_empty_space][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_empty_space][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;52px&#8221;][vc_empty_space height=&#8221;52px&#8221;][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tecvalonline.com\/eng\/valvulas-de-alivio-presion-vacio\/\" \/>\n<meta property=\"og:site_name\" content=\"Tecval\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-14T15:59:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tecvalonline.com\/eng\/valvulas-de-alivio-presion-vacio\/\",\"url\":\"https:\/\/tecvalonline.com\/eng\/valvulas-de-alivio-presion-vacio\/\",\"name\":\"Pressure - Vacuum relief valves - Tecval\",\"isPartOf\":{\"@id\":\"https:\/\/tecvalonline.com\/eng\/#website\"},\"datePublished\":\"2020-11-12T16:52:39+00:00\",\"dateModified\":\"2021-04-14T15:59:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tecvalonline.com\/eng\/valvulas-de-alivio-presion-vacio\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tecvalonline.com\/eng\/valvulas-de-alivio-presion-vacio\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tecvalonline.com\/eng\/valvulas-de-alivio-presion-vacio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/tecvalonline.com\/eng\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pressure &#8211; Vacuum relief valves\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tecvalonline.com\/eng\/#website\",\"url\":\"https:\/\/tecvalonline.com\/eng\/\",\"name\":\"Tecval\",\"description\":\"Somos confiabilidad operacional\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tecvalonline.com\/eng\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pressure - Vacuum relief valves - Tecval","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tecvalonline.com\/eng\/valvulas-de-alivio-presion-vacio\/","og_locale":"en_US","og_type":"article","og_title":"Pressure - Vacuum relief valves - Tecval","og_description":"[vc_row][vc_column width=&#8221;1\/4&#8243;][vc_empty_space][vc_single_image image=&#8221;3812&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221;][vc_single_image image=&#8221;3038&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow_border&#8221; onclick=&#8221;zoom&#8221;][vc_empty_space][vc_column_text]Manufacturing: TECVAL, Colombia Support: TECVAL, Colombia[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space][vc_empty_space][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_empty_space][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;52px&#8221;][vc_empty_space height=&#8221;52px&#8221;][\/vc_column][\/vc_row]","og_url":"https:\/\/tecvalonline.com\/eng\/valvulas-de-alivio-presion-vacio\/","og_site_name":"Tecval","article_modified_time":"2021-04-14T15:59:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tecvalonline.com\/eng\/valvulas-de-alivio-presion-vacio\/","url":"https:\/\/tecvalonline.com\/eng\/valvulas-de-alivio-presion-vacio\/","name":"Pressure - Vacuum relief valves - Tecval","isPartOf":{"@id":"https:\/\/tecvalonline.com\/eng\/#website"},"datePublished":"2020-11-12T16:52:39+00:00","dateModified":"2021-04-14T15:59:52+00:00","breadcrumb":{"@id":"https:\/\/tecvalonline.com\/eng\/valvulas-de-alivio-presion-vacio\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tecvalonline.com\/eng\/valvulas-de-alivio-presion-vacio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tecvalonline.com\/eng\/valvulas-de-alivio-presion-vacio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tecvalonline.com\/eng\/"},{"@type":"ListItem","position":2,"name":"Pressure &#8211; Vacuum relief valves"}]},{"@type":"WebSite","@id":"https:\/\/tecvalonline.com\/eng\/#website","url":"https:\/\/tecvalonline.com\/eng\/","name":"Tecval","description":"Somos confiabilidad operacional","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tecvalonline.com\/eng\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/tecvalonline.com\/eng\/wp-json\/wp\/v2\/pages\/3077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecvalonline.com\/eng\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tecvalonline.com\/eng\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tecvalonline.com\/eng\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tecvalonline.com\/eng\/wp-json\/wp\/v2\/comments?post=3077"}],"version-history":[{"count":6,"href":"https:\/\/tecvalonline.com\/eng\/wp-json\/wp\/v2\/pages\/3077\/revisions"}],"predecessor-version":[{"id":3993,"href":"https:\/\/tecvalonline.com\/eng\/wp-json\/wp\/v2\/pages\/3077\/revisions\/3993"}],"wp:attachment":[{"href":"https:\/\/tecvalonline.com\/eng\/wp-json\/wp\/v2\/media?parent=3077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}